{"id":883,"count":1,"description":"","link":"https:\/\/avido.cn\/th\/tag\/honeycomb-paper\/","name":"\u0e01\u0e23\u0e30\u0e14\u0e32\u0e29\u0e23\u0e31\u0e07\u0e1c\u0e36\u0e49\u0e07","slug":"honeycomb-paper","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/avido.cn\/th\/wp-json\/wp\/v2\/tags\/883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avido.cn\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/avido.cn\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/avido.cn\/th\/wp-json\/wp\/v2\/posts?tags=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}